{"id":828,"date":"2026-02-16T20:08:33","date_gmt":"2026-02-16T19:08:33","guid":{"rendered":"https:\/\/www.muenster.org\/muenster-lublin\/?post_type=tribe_events&#038;p=828"},"modified":"2026-06-27T18:14:58","modified_gmt":"2026-06-27T16:14:58","slug":"sommerfest-2026","status":"publish","type":"tribe_events","link":"https:\/\/www.muenster.org\/muenster-lublin\/event\/sommerfest-2026\/","title":{"rendered":"Sommerfest 2026"},"content":{"rendered":"<p>In diesem Jahr m\u00f6chten wir auf die bestehenden St\u00e4dtepartnerschaften zwischen M\u00fcnster, Lublin und Winnyzja in der Ukraine aufmerksam machen und gemeinsam mit dem Verein \u201eUkrainische Sprache und Kultur in M\u00fcnster e. V.\u201c feiern.<\/p>\n<p>Zum Programm geh\u00f6ren:<\/p>\n<p>\u2022 Begr\u00fc\u00dfung der G\u00e4ste und Einf\u00fchrung in die Dreieckspartnerschaften M\u00fcnster\u2013Lublin\u2013Winnyzja<\/p>\n<p>\u2022 Impulsvortrag von Klaudia Hanisch (Deutsches Polen-Institut) zu den Potenzialen und Herausforderungen deutsch-polnisch-ukrainischer St\u00e4dtepartnerschaften<\/p>\n<p>\u2022 Beitrag von Christiane L\u00f6sel (B\u00fcro Internationales der Stadt M\u00fcnster) zur aktuellen Unterst\u00fctzung f\u00fcr Winnyzja, zum Engagement der B\u00fcrgerinnen und B\u00fcrger in M\u00fcnster sowie zur Rolle Lublins in der Solidarit\u00e4tspartnerschaft<\/p>\n<p>\u2022 Musikalisches Kulturprogramm mit dem ukrainischen Chor \u201eTschervona Kalyna\u201c \u2022 Gemeinsames Grillen, Austausch und geselliges Beisammensein<\/p>\n<p>Treffpunkt ist das Gel\u00e4nde des Clubs Paddel-Sport M\u00fcnster (PSM) von 1923, Wersetimpen 54, 48157 M\u00fcnster.<br \/>\nDie Stra\u00dfe ist gut per Fahrrad erreichbar. Ein Hinweis zur Anfahrt mit dem Auto:<br \/>\nAus M\u00fcnster kommend f\u00e4hrt man am Caf\u00e9 Nobis vorbei (bitte nicht am Bistro Nobis parken!) bis zur Kreuzung und<br \/>\nbiegt dort rechts auf den Alten M\u00fchlenweg ab.<br \/>\nNach 200 m bitte wieder rechts in den Wersetimpen abbiegen (bitte Haus Nr. 54 ins Navi eingeben).<br \/>\nAn der Gabelung bitte erneut rechts abbiegen; nach ca. 100 m erreichen Sie den ausgeschilderten Parkplatz<br \/>\ndes PSM e. V.<\/p>\n<pre>Anmeldung bitte per E-Mail (lublin@muenster.de) oder telefonisch an den Vorstand<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>In diesem Jahr m\u00f6chten wir auf die bestehenden St\u00e4dtepartnerschaften zwischen M\u00fcnster, Lublin und Winnyzja in der Ukraine aufmerksam machen und gemeinsam mit dem Verein \u201eUkrainische Sprache und Kultur in M\u00fcnster [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-828","tribe_events","type-tribe_events","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.muenster.org\/muenster-lublin\/wp-json\/wp\/v2\/tribe_events\/828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muenster.org\/muenster-lublin\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.muenster.org\/muenster-lublin\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.muenster.org\/muenster-lublin\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":4,"href":"https:\/\/www.muenster.org\/muenster-lublin\/wp-json\/wp\/v2\/tribe_events\/828\/revisions"}],"predecessor-version":[{"id":961,"href":"https:\/\/www.muenster.org\/muenster-lublin\/wp-json\/wp\/v2\/tribe_events\/828\/revisions\/961"}],"wp:attachment":[{"href":"https:\/\/www.muenster.org\/muenster-lublin\/wp-json\/wp\/v2\/media?parent=828"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muenster.org\/muenster-lublin\/wp-json\/wp\/v2\/tags?post=828"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.muenster.org\/muenster-lublin\/wp-json\/wp\/v2\/tribe_events_cat?post=828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}